{"id":1,"count":307,"description":"","link":"https:\/\/dps.media\/zh\/%e7%b1%bb%e5%88%ab\/%e6%9c%aa%e5%88%86%e7%b1%bb-6\/","name":"\u672a\u5206\u7c7b","slug":"%e6%9c%aa%e5%88%86%e7%b1%bb-6","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dps.media\/zh\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dps.media\/zh\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dps.media\/zh\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dps.media\/zh\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}